{"id":1592,"date":"2015-02-20T13:45:15","date_gmt":"2015-02-20T12:45:15","guid":{"rendered":"http:\/\/www.katzen.de\/magazin\/?p=1592"},"modified":"2015-02-20T13:45:15","modified_gmt":"2015-02-20T12:45:15","slug":"katze-allein-zu-haus-was-treiben-unsere-racker-ohne-uns","status":"publish","type":"post","link":"https:\/\/www.katzen.de\/magazin\/katze-allein-zu-haus-was-treiben-unsere-racker-ohne-uns\/","title":{"rendered":"Katze allein zu Haus: Was treiben unsere Racker ohne uns?"},"content":{"rendered":"<p>Immer mehr Menschen kommen nicht auf den Hund, sondern auf die Katze, die daf\u00fcr bekannt ist, ein individuelles Wesen zu sein. Mit ihr ist der Mensch nicht gezwungen, mehrere Male am Tag Gassi gehen zu m\u00fcssen, und ebenso braucht er sich nicht davor f\u00fcrchten, dass sich die Nachbarn \u00fcber eine \u00fcberm\u00e4\u00dfige Ger\u00e4uschbel\u00e4stigung durch stundenlanges Bellen beschweren werden, wenn der Besitzer am Tag auf der Arbeit ist. Dar\u00fcber hinaus ist es zweifelsohne m\u00f6glich, den Racker auch mal \u00fcber Nacht oder am Wochenende alleine in den eigenen vier W\u00e4nden zu lassen. Aber dennoch mag sich so mancher Katzenhalter fragen, was sein frecher Vierbeiner eigentlich macht, wenn er alleine zu Hause ist.<\/p>\n<p><strong>Futtervorrat bereitstellen \u2013 und alles andere aus dem Weg r\u00e4umen<\/strong><\/p>\n<p>Grunds\u00e4tzlich sollte immer\u00a0<a href=\"http:\/\/www.katzenwiefelix.de\" target=\"_blank\">ausreichend Katzenfutter\u00a0<\/a>bereitstehen, f\u00fcr den Fall, dass es mal sp\u00e4ter werden kann oder sich der Katzenbesitzer ein erholsames Wochenende g\u00f6nnen m\u00f6chte. Denn gerade Katzen, die von Hunger geplagt sind, k\u00f6nnen schon mal die Wohnung umdekorieren. Sie begeben sich nicht selten auf die Suche nach etwas Essbarem und werden in solch einem Fall noch nicht einmal vor einer vergessenen Chipst\u00fcte oder einer angefangenen Tafel Schokolade haltmachen. Beides geh\u00f6rt allerdings keineswegs auf den Speiseplan des Vierbeiners und kann sogar schwere Erkrankungen mit sich ziehen. Manche frechen Racker sind tats\u00e4chlich wahre Meister darin, Schr\u00e4nke oder den Brotkasten zu \u00f6ffnen, um irgendetwas zu ergattern, was nach Nahrung riecht und schmeckt. Mit einem gut gef\u00fcllten Fress- und Wassernapf kann dies Problem jedoch verhindert werden. Wer allerdings denkt, dass die Katze sich den Bauch so lange vollschlagen wird, bis der Napf leer ist, dem sei gesagt, dass dies keineswegs der Fall sein wird. Sicherlich mag es Ausnahmen geben, die die Regel best\u00e4tigen, aber im Normalfall merken sie sehr genau, wann ihr Hungergef\u00fchl nachgelassen hat und werden sich dann vorl\u00e4ufig vom Futternapf abwenden, um diesen nach einigen Stunden nochmals aufzusuchen.<br \/>\n<strong><br \/>\nLangeweile \u2013 und nun?<\/strong><\/p>\n<p>Auch wenn viele Menschen noch immer denken m\u00f6gen, Katzen w\u00e4ren Einzelg\u00e4nger, so kann auch ihnen sprichw\u00f6rtlich die &#8222;Decke auf dem Kopf fallen&#8220;. Denn ohne einen geeigneten Spielkameraden oder entsprechendes Spielzeug und einem Kratzbaum wird den Stubentigern schnell langweilig werden. Wenn sie ihre aufgestaute Energie nicht loswerden k\u00f6nnen, bauen sich Frustrationen auf, die dann abreagiert werden m\u00fcssen. In solch einem Fall ist die Wohnungseinrichtung nicht mehr sicher. Abgerollte Toilettenpapierrollen sind noch der harmloseste Streich, der angerichtet wird. Tiergerechte Besch\u00e4ftigungs-M\u00f6glichkeiten k\u00f6nnen jedoch daf\u00fcr sorgen, dass sich selbst der gem\u00fctlichste Kater nach Herzenslust abreagieren kann und die Wohnung nicht vollends auf den Kopf gestellt wird. Dar\u00fcber hinaus werden durch das Spielen die Sinne der Katze trainiert und die Beziehung zwischen ihr und dem Menschen gest\u00e4rkt.<\/p>\n<p><strong>Das Zuhause ist ein riesiger Spielplatz<\/strong><\/p>\n<p>Zu den besonders beliebten Spielm\u00f6glichkeiten geh\u00f6ren Korken, B\u00e4lle, Fellm\u00e4use oder einfach leere \u00dcberraschungseier. Da Katzen alles lieben, was Ger\u00e4usche macht, k\u00f6nnen die \u00dcberraschungseier einfach mit Steinchen gef\u00fcllt werden und bei den Fellm\u00e4usen kann auf die quiekende Variante zur\u00fcckgegriffen werden. Hauptsache, der Racker kann nach Herzenslust die ger\u00e4uschvollen Spielartikel durch die Wohnung schie\u00dfen und hinterherjagen. Ebenfalls sehr beliebt sind Spielb\u00e4lle, die mit kleinen L\u00f6chern versehen sind und sich mit <a href=\"http:\/\/www.katzenwiefelix.de\/PRODUKTE\/Pages\/range.aspx#treats\" target=\"_blank\">sch\u00f6nen Leckerlis<\/a> f\u00fcllen lassen. W\u00e4hrend des Herumtobens fallen diese dann heraus, was sie als zus\u00e4tzliche Belohnung ansehen wird. Diese Spielb\u00e4lle geh\u00f6ren zu dem Intelligenzspielzeug, mit dem die Fellnase ihre ganz eigenen Jagdtechniken und Strategien entwickeln wird, um an ihre &#8222;Beute&#8220; zu gelangen. Eine noch gr\u00f6\u00dfere Freude kann man seinem vierbeinigen Weggef\u00e4hrten allerdings machen, wenn man noch einen zweiten Katzenkumpel dazu holt. Zusammen k\u00f6nnen sie spielen, toben, jagen, gemeinsam aus dem Fenster nach ihrem Menschen Ausschau halten oder schlafen. Denn geteilte Freude ist in diesem Fall doppelte Freude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer mehr Menschen kommen nicht auf den Hund, sondern auf die Katze, die daf\u00fcr bekannt ist, ein individuelles Wesen zu sein. Mit ihr ist der Mensch nicht gezwungen, mehrere Male am Tag Gassi gehen zu m\u00fcssen, und ebenso braucht er sich nicht davor f\u00fcrchten, dass sich die Nachbarn \u00fcber eine \u00fcberm\u00e4\u00dfige Ger\u00e4uschbel\u00e4stigung durch stundenlanges Bellen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[445,446],"tags":[475,509,510,284],"_links":{"self":[{"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/posts\/1592"}],"collection":[{"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":1,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"predecessor-version":[{"id":1594,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/posts\/1592\/revisions\/1594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/media\/1593"}],"wp:attachment":[{"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.katzen.de\/magazin\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}